{"id":575,"date":"2024-10-06T16:36:56","date_gmt":"2024-10-06T20:36:56","guid":{"rendered":"https:\/\/timbirichevida.com\/?p=575"},"modified":"2025-11-01T16:24:22","modified_gmt":"2025-11-01T20:24:22","slug":"blogp13","status":"publish","type":"post","link":"https:\/\/timbirichevida.com\/es\/blogp13\/","title":{"rendered":"\u00bfQu\u00e9 es el coaching de salud?"},"content":{"rendered":"<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"1024\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=1024%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-576\" style=\"width:502px;height:auto\" srcset=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=850%2C850&amp;ssl=1 850w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?resize=100%2C100&amp;ssl=1 100w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/10\/coach-amarie.png?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"\">\u00a1Qu\u00e9 rico que conectes conmigo! En este Sunday Blog Day, contesto las preguntas m\u00e1s frecuentes sobre lo que es el coaching de salud. y como yo, Coach de Salud Integrada, puedo ayudarte en tus metas de salud.<\/p>\n\n\n\n<p class=\"\">Entre las cosas m\u00e1s importantes que debe saber es que el coaching de salud trata temas, precisamente de salud. Hay muchas personas por ah\u00ed que se hacen llamar coaches de salud que te hablan de informaci\u00f3n de nutrici\u00f3n o alg\u00fan otro tema de salud simplemente porque es la onda del momento. Es importante que sepas que, a la hora de buscar los servicios de un coach, debes asegurarte que tenga certificaciones de escuelas acreditadas en coaching de salud. Dicho lo anterior, aqu\u00ed contesto preguntas sobre el Coaching de Salud.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfQu\u00e9 es el Coaching o la Consultor\u00eda de Salud?<\/strong><\/p>\n\n\n\n<p class=\"\">El coaching de salud es una alianza de colaboraci\u00f3n entre un coach y su cliente, en la que se discute el historial de salud del cliente, se abordan las preocupaciones iniciales, as\u00ed como las restricciones, las consideraciones de estilo de vida, y los objetivos a largo y corto plazo, con el prop\u00f3sito de llevar a cabo reuniones, dentro de un porgrama de trabajo flexible, en el que el coach proprciona responsabilidad para apoyar a los clientes en sus procesos individuales de salud y bienestar.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfCu\u00e1l es mi enfoque en el Coaching de Salud?<\/strong><\/p>\n\n\n\n<p class=\"\">Puedes encontrar coaches de salud que se enfocan en el embarazo o en enfermedades autoinmunes o en una dieta particular o el sistema reproductor o en lactancia, en fin&#8230; No somos de una sola talla.<\/p>\n\n\n\n<p class=\"\">En mi caso, mi enfoque es en la nutrici\u00f3n. Creo en que la idea de que una nutrici\u00f3n \u00fanica, integrada y funcional puede actuar como medicina preventiva, es posible y es real porque permite mantener el equilibrio y la salud de tu cuerpo de forma sostenible. Adem\u00e1s, es flexible y adaptable para que puedas avanzar en edad haciendo todo lo que te encanta hacer. <\/p>\n\n\n\n<p class=\"\">La alimentaci\u00f3n es una necesidad b\u00e1sica y de supervivencia que, para lograr conexi\u00f3n directa con nuestra salud y bienestar, requiere crear consciencia de lo que servimos en nuestro plato.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfEn que se diferencia un Coach de Salud en ver a un m\u00e9dico o terap\u00e9uta?<\/strong><\/p>\n\n\n\n<p class=\"\">Los m\u00e9dicos y terap\u00e9utas diagnostican y tratan afecciones de salud y salud mental. Los coaches de salud no somos profesionales de salud mental ni m\u00e9dicos, pero podemos proporcionarte informaci\u00f3n y apoyo para que mejores tu estlilo de vida a trav\u00e9s de cambios en comportamiento y alivies algunos de los s\u00edntmas de estr\u00e9s y ansiedad. Nuestro trabajo colaborativo no tiene el prop\u00f3sito de sustituir la atenci\u00f3n m\u00e9dica cuando la necesites, por lo que, de surgir durante una consulta de coaching, te dejar\u00e9 saber que debes acudir a uno.<\/p>\n\n\n\n<p class=\"\">El coaching es una experiencia basada en ti como cliente, donde facilito el proceso para que logres articular tus objetivos y avance hacia tus metas deseadas. Como consultora, simplifico el proceso para que puedas conectar los puntos entre qui\u00e9n eres en este momento y qui\u00e9n quieren ser, puedas definir y establecer tus metas para que logres el \u00e9xito en los cambios que deseas, llevando a cabo cambios sostenibles que mejoren tu estado de salud y felicidad. Durante tu proceso, te escuchar\u00e9 activamente, te apoyar\u00e9 y te orientar\u00e9 para ayudarte a navegar por el amplio mundo de los contradictorios consejos de nutrici\u00f3n y que puedas explorar qu\u00e9 es lo mejor que funciona para ti.<\/p>\n\n\n\n<p class=\"\">Si te atiendes con un m\u00e9dico o terap\u00e9uta, como coach de salud, puedo trabajar con ellos para brindarte una experiencia de coaching hol\u00edstica.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfEn qu\u00e9 se diferencia el coaching de trabajar con un entrenador personal?<\/strong><\/p>\n\n\n\n<p class=\"\">De ordinario, un coach de salud no instruyen a los clientes sobre ejercicios espec\u00edficos ni crear\u00e1n programas de ejercicios. M\u00e1s bien, ayudan a sus clientes a crear objetivos que les permitan cumplir con sus rutinas de ejercicio deseasdas. <\/p>\n\n\n\n<p class=\"\">En mi coaching de salud, tendr\u00e1s disponible un programa donde te ayudar\u00e9 a crear esos objetivos para que, si haces ejercicio por tu cuenta o entrenas con un entrenador personal, puedas cumplir con las rutinas de ejercicio que ya realizas. <\/p>\n\n\n\n<p class=\"\">Pero, como siempre estoy educ\u00e1ndome en estos temas para darte una experiencia \u00fanica con mi coachign de slaud, estoy completando una certificaci\u00f3n en OPEX Fitness, por lo que te ofrezco un programa de coaching que incluye el dise\u00f1o de programaci\u00f3n de entrenamiento f\u00edsico que se adapte a tus metas de salud. Esto significa que, en mi caso, tendr\u00e1s un 2&#215;1, una coach de salud y una entrenadora personal.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfPuede un Coach de Salud crear planes de comida para t?<\/strong><\/p>\n\n\n\n<p class=\"\">A esto me refer\u00eda en el inicio de esta publicaci\u00f3n. Encontrar\u00e1s mucha gente que te dir\u00e1 c\u00f3mo debes comer, lo que debes comer y te crear\u00e1n planes de comida alegadamente dise\u00f1ados para ti.<\/p>\n\n\n\n<p class=\"\">El asunto es que solamente los m\u00e9dicos y dietistas y nutricionistas licenciados son los que te har\u00e1n las recomendaciones nutricionales basadas en tu historial m\u00e9dico y tus necesidades, incluyendo la prescripci\u00f3n de dietas.<\/p>\n\n\n\n<p class=\"\">Los Coaches de Salud, como yo, no creamos planes de comida, sino que te empoderamos para que busques los alimentos y las dietas que funcionen para ti, y brindamos apoyo y responsabilidad para que realices este tipo de cambios en tu vida.<\/p>\n\n\n\n<p class=\"\">Si te atiendes con un diestista o nutricionista licenciado, como coach de salud puedo trabajar con ellos para brindarte una experiencia de coaching hol\u00edstica.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfCu\u00e1nto tiempo tarda en que veas cambios en un Programa de Coaching de Salud?<\/strong><\/p>\n\n\n\n<p class=\"\">Cada persona es \u00fanica y diferente, y por eso los programas que ofrezco son individualizados, que fluyen con tus curiosidades, capacidades y experiencias de vida, por lo que son adaptables a tus metas de salud.<\/p>\n\n\n\n<p class=\"\">El tiempo que te tome ver cambios depender\u00e1n de tu motivaci\u00f3n y de tu compromiso y trabajo en colaboraci\u00f3n conmigo.<\/p>\n\n\n\n<p class=\"\"><strong>\u00bfC\u00f3mo funcionan las sesiones de coaching y c\u00f3mo nos comunicaremos entre sesiones?<\/strong><\/p>\n\n\n\n<p class=\"\">Dentro del programa de coaching te acompa\u00f1o en tu proceso de transformaci\u00f3n. Colaboro contigo y te ayudo a que puedas descubrir qu\u00e9 quieres hacer y por qu\u00e9, definas tus metas y tu paso, y que puedas entender con empat\u00eda y compasi\u00f3n tus procesos para que tomes las decisiones que mejor te benefician.<\/p>\n\n\n\n<p class=\"\">Trabajaremos en conjunto para encontrar tu propio plan personal. Mi intenci\u00f3n es capacitarte para que aprendas c\u00f3mo descifrar las necesidades \u00fanicas de tu cuerpo y aprender\u00e1s c\u00f3mo tomar el control de tu propio bienestar. <\/p>\n\n\n\n<p class=\"\">En este proceso, la comunicaci\u00f3n es clave y ser\u00e1 diferente. Tendr\u00e1s sesiones cada mes o dos veces al mes, as\u00ed como comunicaci\u00f3n entre sesiones para medir tu progreso y ayudarte a entender cualqueir desaf\u00edo que puedas estar experimentando. Lo importante en nuestra comunicaci\u00f3n es que siempre muestres honestidad acerca de tu experiencia para poder ajustar tu programa hacia la direcci\u00f3n correcta que te lleve al logro de tus metas.<\/p>\n\n\n\n<p class=\"\">Espero, al menos, haber contestado preguntas claves e importantes si est\u00e1s considerando buscar los servicios de un coach de salud.<\/p>\n\n\n\n<p class=\"\">Me encantar\u00eda ser tu coach y que tengamos esa alianza colaborativa en la que pueda ayudarte a que realices todo lo que te propongas para mejorar tu calidad de vida y tu salud en tu Timbiriche Vida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"548\" height=\"308\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/08\/Firma-AMarie-1.png?resize=548%2C308&#038;ssl=1\" alt=\"\" class=\"wp-image-358\" style=\"width:242px;height:auto\" srcset=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/08\/Firma-AMarie-1.png?w=548&amp;ssl=1 548w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/08\/Firma-AMarie-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/08\/Firma-AMarie-1.png?resize=18%2C10&amp;ssl=1 18w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/figure>\n\n\n\n<p class=\"\">Si tienes preguntas o quieres m\u00e1s detalles, <a href=\"http:\/\/timbirichevida.com\/contactame\" title=\"cont\u00e1ctame\">cont\u00e1ctame<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Qu\u00e9 rico que conectes conmigo! En este Sunday Blog Day, contesto las preguntas m\u00e1s frecuentes sobre lo que es el coaching de salud. y como yo, Coach de Salud Integrada, puedo ayudarte en tus metas de salud. Entre las cosas m\u00e1s importantes que debe saber es que el coaching de salud trata temas, precisamente de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-575","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/comments?post=575"}],"version-history":[{"count":5,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts\/575\/revisions"}],"predecessor-version":[{"id":1486,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts\/575\/revisions\/1486"}],"wp:attachment":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/categories?post=575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/tags?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}