{"id":910,"date":"2024-12-01T09:30:00","date_gmt":"2024-12-01T13:30:00","guid":{"rendered":"https:\/\/timbirichevida.com\/?p=910"},"modified":"2025-11-01T16:23:12","modified_gmt":"2025-11-01T20:23:12","slug":"blogp17","status":"publish","type":"post","link":"https:\/\/timbirichevida.com\/es\/blogp17\/","title":{"rendered":"Planificar comidas, \u00bfvale la pena?"},"content":{"rendered":"<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/11\/meal-planning.jpg?ssl=1\" alt=\"\" class=\"wp-image-915\" style=\"width:686px;height:auto\"\/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>\u00a1Qu\u00e9 rico que conectes conmigo! Espero hayas pasado un D\u00eda de Acci\u00f3n de Gracias espectacular junto a esas personas que m\u00e1s quieres. Y como siempre pasa, supongo que estar\u00e1s comiendo pavo, o lo que hayan preparado para el almuerzo o cena de Acci\u00f3n de Gracias, por lo que queda del fin de semana y, posiblemente, la semana entrante. Esto me lleva al tema de este Sunday Blog Day, si planificar comidas o \u201cmeal planning\u201d vale la pena.<\/p>\n\n\n\n<p>De entrada, te comento que, a m\u00ed, personalmente, no me gusta mucho hacer meal planning, pero eso no significa que pueda funcionar para ti. Antes de decirte porque no me es funcional, hablemos de qu\u00e9 significa el \u201cmeal planning\u201d.<\/p>\n\n\n\n<p>La planificaci\u00f3n de comidas es el proceso de decidir con anticipaci\u00f3n qu\u00e9 comidas se van a preparar y consumir durante un per\u00edodo espec\u00edfico. En su mayor\u00eda, lo ideal es llevar a cabo esta planificaci\u00f3n para una semana. Aunque no lo creas, la planificaci\u00f3n de comidas incluye seleccionar recetas, crear una lista de compras basada en los ingredientes necesarios y, en ocasiones, la preparaci\u00f3n previa de algunos elementos para facilitar la cocci\u00f3n diaria. Adem\u00e1s, requiere que planifiques, en tu agenda, el tiempo necesario que te tomar\u00e1 llevar a cabo la actividad, no solo de la planificaci\u00f3n de comidas, sino tambi\u00e9n ese tiempo que usar\u00e1s para cocinar y almacenar. \u00bfTe suena familiar a cuando planificaste la comida de Acci\u00f3n de Gracias?<\/p>\n\n\n\n<p>El meal planning es de gran ayuda si quieres hacer cambios en tu alimentaci\u00f3n porque permite enfoque en que esa es la comida que te debes comer durante la semana porque ya est\u00e1 preparada. Adem\u00e1s, ayuda a que puedas maximizar tu tiempo y dedicarlo a otras cosas y, claro est\u00e1, siempre que hayas planificado y cumplas con ese espacio que separaste para planificar tus comidas.<\/p>\n\n\n\n<p>De hecho, en el mundo del fitness es muy com\u00fan que la primera recomendaci\u00f3n que te ofrezcan sea el meal planning por lo que mencion\u00e9 en el p\u00e1rrafo anterior. En efecto, tiene grandes beneficios:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ahorro de tiempo: Al planificar las comidas con anticipaci\u00f3n, reduces el tiempo que pasas decidiendo qu\u00e9 comer y cocinando cada d\u00eda.<\/li>\n\n\n\n<li>Mejor organizaci\u00f3n: Puedes hacer una lista de compras m\u00e1s precisa, evitando compras impulsivas y desperdicio de alimentos.<\/li>\n\n\n\n<li>Ahorro de dinero: Al saber exactamente lo que necesitas comprar, es menos probable que gastes en cosas innecesarias.<\/li>\n\n\n\n<li>Comidas saludables: Te permite planificar opciones m\u00e1s saludables y balanceadas, evitando la tentaci\u00f3n de recurrir a comida r\u00e1pida.<\/li>\n\n\n\n<li>Reducci\u00f3n del estr\u00e9s: Con un plan claro, eliminas la presi\u00f3n de tener que decidir qu\u00e9 cocinar cada d\u00eda.<\/li>\n<\/ul>\n\n\n\n<p>Sin embargo, tambi\u00e9n tiene sus contras:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Falta de flexibilidad: Puede ser restrictivo si tus planes cambian y no puedes seguir el plan de comidas.<\/li>\n\n\n\n<li>Tiempo inicial de preparaci\u00f3n: Requiere tiempo y esfuerzo para planificar las comidas y preparar los ingredientes con anticipaci\u00f3n.<\/li>\n\n\n\n<li>Monoton\u00eda: Comer lo mismo varias veces puede volverse aburrido si no se var\u00eda el men\u00fa.<\/li>\n\n\n\n<li>Desperdicio potencial: Si no sigues el plan, los ingredientes pueden echarse a perder.<\/li>\n\n\n\n<li>Dificultad para adaptarse: Puede ser un desaf\u00edo para quienes no est\u00e1n acostumbrados a planificar con tanta anticipaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>Aunque me identifico con sus beneficios, como por ejemplo, el ahorro de tiempo, la mejor organizaci\u00f3n y el beneficio de comidas saludables, la falta de flexibilidad y la monoton\u00eda, son las razones por las cuales no me funciona el meal planning. Me aburro con facilidad de comer lo mismo, por lo que son m\u00e1s las ocasiones que la comida se me da\u00f1a. Por otro lado, en ocasiones, lo siento restrictivo, en especial, si mis planes cambian.<\/p>\n\n\n\n<p>Sin embargo, esto no significa que descarte hacer planificaci\u00f3n de comidas del todo. He sabido planificar para tiempos cortos. En vez de una semana, pudiera planificar comidas para tres d\u00edas, por ejemplo. La decisi\u00f3n de planificar comidas depender\u00e1, en gran medida, de las actividades que se encuentran en mi agenda.<\/p>\n\n\n\n<p>Y esta es mi recomendaci\u00f3n para ti. Si quieres intentar el meal planning, \u00a1adelante! Puede traerte grandes beneficios, en especial si quieres desarrollar mejores h\u00e1bitos de alimentaci\u00f3n, porciones u horarios de comidas. Para comenzar:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ve a tu calendario y escoge una fecha y hora en el que vas a escoger los alimentos de tu men\u00fa y el tiempo para preparar las comidas. La mayor\u00eda de las personas suelen escoger los domingos, pero no tiene que ser as\u00ed. Verifica tu agenda y busca esas ventanas de espacios libres que tienes disponible para esta actividad.<\/li>\n\n\n\n<li>Ponte una alarma en tu tel\u00e9fono o en tu calendario que te sirva de recordatorio.<\/li>\n\n\n\n<li>Haz una lista de compras para que sea m\u00e1s f\u00e1cil la visita al supermercado y puedas seleccionar alimentos saludables. La visita al supermercado tambi\u00e9n pudieras agendarla.<\/li>\n\n\n\n<li>Ten a la mano y listo todo lo que necesites para cocinar, incluyendo los envases de almacenamiento. \u00bfSab\u00edas que es mejor guardar las comidas en envases de cristal que en los de pl\u00e1stico? Recuerda que estar\u00e1s consumiendo alimentos previamente preparados y los envases de cristal resultan ser mejores, no solo para el ambiente, sino tambi\u00e9n para tu salud, que utilizar envases de pl\u00e1sticos, m\u00e1s a\u00fan si calentar\u00e1s tus comidas en el microondas.<\/li>\n\n\n\n<li>Utiliza recetas o simplemente da paso a tu creatividad en la cocina.<\/li>\n\n\n\n<li>Incluye meriendas saludables en tu planificaci\u00f3n.<\/li>\n\n\n\n<li>Almacena tus alimentos poni\u00e9ndoles una etiqueta a los envases por cada d\u00eda que vas a consumirlos, as\u00ed desarrollar\u00e1s el h\u00e1bito de cumplir con tu consumo de alimentos planificados.<\/li>\n<\/ol>\n\n\n\n<p>Si lo trataste y entiendes que no te funciona, como me pasa a m\u00ed, no importa, pero si te recomiendo que hagas repaso de por qu\u00e9 entiendes que no te fue funcional. As\u00ed podr\u00e1s decidir si es algo que puedes considerar en ciertas ocasiones, como hago yo.<\/p>\n\n\n\n<p>\u00bfVale la pena el meal planning? \u00a1Claro que s\u00ed! Ya sea que lo hagas para una semana o para cortos per\u00edodos de tiempo, puede ser de beneficio si lo adaptas a tus necesidades y tus metas. &nbsp;<\/p>\n\n\n\n<p>Como te mencion\u00e9 al principio, el meal planning no es mi favorito, pero s\u00ed hago planificaci\u00f3n de comidas en momentos en que mi agenda semanal se ve sumamente ocupada, as\u00ed ahorro tiempo y reduzco estr\u00e9s en mi Timbiriche Vida.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"548\" height=\"308\" loading=\"lazy\" src=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/11\/Firma-AMarie.png?resize=548%2C308&#038;ssl=1\" alt=\"\" class=\"wp-image-883\" style=\"width:188px;height:auto\" srcset=\"https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/11\/Firma-AMarie.png?w=548&amp;ssl=1 548w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/11\/Firma-AMarie.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/timbirichevida.com\/wp-content\/uploads\/2024\/11\/Firma-AMarie.png?resize=18%2C10&amp;ssl=1 18w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/figure>\n\n\n\n<p>\u00bfNecesitas ayuda para dise\u00f1ar una planificaci\u00f3n de alimentos y establecer tus metas de salud? Mi coaching de salud integrada es tu alternativa:<\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.34%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/timbirichevida.com\/conversemos\">\u00a1Conversemos!<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 is-style-outline is-style-outline--2\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/timbirichevida.com\/product\/consulta\">Consulta<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 is-style-outline is-style-outline--3\"><a class=\"wp-block-button__link wp-element-button\" href=\"http:\/\/timbirichevida.com\/programavip\">Timbiriche Vida VIP<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a1Qu\u00e9 rico que conectes conmigo! Espero hayas pasado un D\u00eda de Acci\u00f3n de Gracias espectacular junto a esas personas que m\u00e1s quieres. Y como siempre pasa, supongo que estar\u00e1s comiendo pavo, o lo que hayan preparado para el almuerzo o cena de Acci\u00f3n de Gracias, por lo que queda del fin de semana y, posiblemente, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[28,24,22,26,27,21,25,29,23],"class_list":["post-910","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-balance","tag-blog-personal","tag-relacion-mente-y-cuerpo","tag-salud","tag-salud-integrada","tag-timbiriche","tag-vida","tag-vida-integrada","tag-vida-saludable"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts\/910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/comments?post=910"}],"version-history":[{"count":9,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts\/910\/revisions"}],"predecessor-version":[{"id":1482,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/posts\/910\/revisions\/1482"}],"wp:attachment":[{"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/media?parent=910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/categories?post=910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timbirichevida.com\/es\/wp-json\/wp\/v2\/tags?post=910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}